{"id":7251,"date":"2024-02-13T15:47:20","date_gmt":"2024-02-13T18:47:20","guid":{"rendered":"https:\/\/gopunta.uy\/noticias\/?p=7251"},"modified":"2024-02-13T15:47:21","modified_gmt":"2024-02-13T18:47:21","slug":"migracion-de-mariposas-pavo-real-en-uruguay","status":"publish","type":"post","link":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/","title":{"rendered":"Migraci\u00f3n de mariposas pavo real en Uruguay"},"content":{"rendered":"\n<p>En este mes de febrero se nota la presencia de esta mariposa, deslaz\u00e1ndose en grandes cantidades. Son en su mayor\u00eda son de color canela y en sus alas llevan unos ocelos que simulan un Pavo Real y de ah\u00ed su nombre, seg\u00fan describe Gabriela Bentancur.<\/p>\n\n\n\n<p>La especie tiene este comportamiento de migraci\u00f3n y su ruta es de Este a Oeste. No se tiene mucha informaci\u00f3n sobre la cantidad, pero son miles. Est\u00e1n presentes en las playas, jardines y tambi\u00e9n en la Ruta Interbalnearia, entre otros espacios.<\/p>\n\n\n\n<p>Pr\u00f3ximamente se estar\u00e1 publicando tambi\u00e9n un libro donde se podr\u00e1 aprender sobre otra especie conocida, como lo es la \u201cMonarca del Sur\u201d. El material parte de un trabajo realizado por tres a\u00f1os en el mariposario del Instituto Uruguayo Argentino (IUA), espacio que cuenta con una zona de cr\u00eda, \u00e1rea de vuelo y jard\u00edn de mariposas a cielo abierto.<\/p>\n\n\n\n<p>La profesora de Biolog\u00eda y autora del libro La Mariposa Monarca del Sur, Melina Muniz Guerendia\u00edn, adelant\u00f3 que se encuentra trabajando en la culminaci\u00f3n del material.<\/p>\n\n\n\n<p>Adem\u00e1s hemos conversado con ella para ver c\u00f3mo atraer las mariposas a nuestro jard\u00edn:<\/p>\n\n\n\n<p>Para ello es necesario saber m\u00e1s acerca de la vida de estos asombrosos insectos que son lepid\u00f3pteros pertenecientes al f\u00edlum artr\u00f3podo. Lepid\u00f3pteros significa alas con escamas.<\/p>\n\n\n\n<p>El ciclo de vida de las mariposas comprende cuatro fases: huevo, oruga, cris\u00e1lida y mariposa.<\/p>\n\n\n\n<p>Lo m\u00e1s importante es que \u201csi las queremos de visita, tenemos que contar con dos clases de plantas: hospedadoras y nectar\u00edferas. Las plantas hospedadoras son grupos de plantas donde la mariposa pone los huevos y la oruga se alimenta, mientras que las nectar\u00edferas son aquellas necesarias para que la mariposa se alimente, ricas en n\u00e9ctar y con flores llamativas, por ejemplo: Lantana, Zinnias y Verbenas\u201d.<\/p>\n\n\n\n<p>Muniz Muniz Guerendiain tambi\u00e9n recomienda tres plantas que se pueden tener en el hogar para criar desde el huevo a tres mariposas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asclepias, hospedadores de la mariposa Monarca del Sur &#8211; Danaus erippus.<\/li>\n\n\n\n<li>Passiflora caerulea conocida como Mburucuy\u00e1, hospedadora de la mariposa Espejito &#8211; Agraulis vanillae.<\/li>\n\n\n\n<li>Tropaeolum majus es el nombre cient\u00edfico de Taco de Reina, planta hospedadora de la mariposa Blanca -Leptophobia aripa.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En este mes de febrero se nota la presencia de esta mariposa, deslaz\u00e1ndose en grandes cantidades. Son en su mayor\u00eda son de color canela y en sus alas llevan unos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-7251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sector-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Migraci\u00f3n de mariposas pavo real en Uruguay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Migraci\u00f3n de mariposas pavo real en Uruguay\" \/>\n<meta property=\"og:description\" content=\"En este mes de febrero se nota la presencia de esta mariposa, deslaz\u00e1ndose en grandes cantidades. Son en su mayor\u00eda son de color canela y en sus alas llevan unos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-13T18:47:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-13T18:47:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Virginia de los Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginia de los Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/\",\"url\":\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/\",\"name\":\"Migraci\u00f3n de mariposas pavo real en Uruguay\",\"isPartOf\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg\",\"datePublished\":\"2024-02-13T18:47:20+00:00\",\"dateModified\":\"2024-02-13T18:47:21+00:00\",\"author\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/5106c264cd335a5bef58c3736d6e627b\"},\"breadcrumb\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#primaryimage\",\"url\":\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg\",\"contentUrl\":\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg\",\"width\":1600,\"height\":765},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/gopunta.uy\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Migraci\u00f3n de mariposas pavo real en Uruguay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/#website\",\"url\":\"https:\/\/gopunta.uy\/noticias\/\",\"name\":\"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado\",\"description\":\"Noticias del Portal Inmobiliario GoPunta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gopunta.uy\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/5106c264cd335a5bef58c3736d6e627b\",\"name\":\"Virginia de los Santos\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Migraci\u00f3n de mariposas pavo real en Uruguay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/","og_locale":"es_ES","og_type":"article","og_title":"Migraci\u00f3n de mariposas pavo real en Uruguay","og_description":"En este mes de febrero se nota la presencia de esta mariposa, deslaz\u00e1ndose en grandes cantidades. Son en su mayor\u00eda son de color canela y en sus alas llevan unos [&hellip;]","og_url":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/","og_site_name":"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado","article_published_time":"2024-02-13T18:47:20+00:00","article_modified_time":"2024-02-13T18:47:21+00:00","og_image":[{"width":1600,"height":765,"url":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg","type":"image\/jpeg"}],"author":"Virginia de los Santos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Virginia de los Santos","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/","url":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/","name":"Migraci\u00f3n de mariposas pavo real en Uruguay","isPartOf":{"@id":"https:\/\/gopunta.uy\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#primaryimage"},"image":{"@id":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#primaryimage"},"thumbnailUrl":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg","datePublished":"2024-02-13T18:47:20+00:00","dateModified":"2024-02-13T18:47:21+00:00","author":{"@id":"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/5106c264cd335a5bef58c3736d6e627b"},"breadcrumb":{"@id":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#primaryimage","url":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg","contentUrl":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/02\/0527ECD7-DEDB-48F7-82AB-8F7B66ABA627.jpeg","width":1600,"height":765},{"@type":"BreadcrumbList","@id":"https:\/\/gopunta.uy\/noticias\/2024\/02\/13\/migracion-de-mariposas-pavo-real-en-uruguay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gopunta.uy\/noticias\/"},{"@type":"ListItem","position":2,"name":"Migraci\u00f3n de mariposas pavo real en Uruguay"}]},{"@type":"WebSite","@id":"https:\/\/gopunta.uy\/noticias\/#website","url":"https:\/\/gopunta.uy\/noticias\/","name":"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado","description":"Noticias del Portal Inmobiliario GoPunta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gopunta.uy\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/5106c264cd335a5bef58c3736d6e627b","name":"Virginia de los Santos"}]}},"_links":{"self":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts\/7251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/comments?post=7251"}],"version-history":[{"count":1,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts\/7251\/revisions"}],"predecessor-version":[{"id":7253,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts\/7251\/revisions\/7253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/media\/7252"}],"wp:attachment":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/media?parent=7251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/categories?post=7251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/tags?post=7251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}