{"id":7363,"date":"2024-07-04T14:03:13","date_gmt":"2024-07-04T17:03:13","guid":{"rendered":"https:\/\/gopunta.uy\/noticias\/?p=7363"},"modified":"2024-07-04T14:03:15","modified_gmt":"2024-07-04T17:03:15","slug":"punta-del-este-prepara-los-festejos-de-sus-117-anos","status":"publish","type":"post","link":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/","title":{"rendered":"Punta del Este prepara los festejos de sus 117 a\u00f1os"},"content":{"rendered":"\n<p>Este viernes 5 de julio se celebra el 117\u00ba aniversario de la ciudad. El Municipio a trav\u00e9s del alcalde Javier Carballal, concejales y funcionarios, invitan a participar a la poblaci\u00f3n en general de las actividades programadas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A la hora 11:30 esta previsto el desfile de la Banda de la Divisi\u00f3n de Ej\u00e9rcito IX y la Banda de la Brigada de Caballer\u00eda N\u00ba 2.<\/p>\n\n\n\n<p>El recorrido ser\u00e1 por la avenida Gorlero desde calle 32 hasta llegar frente al Municipio.<\/p>\n\n\n\n<p>All\u00ed los esperaran la Orquesta Departamental de Maldonado, Banda de Parada de la Armada Nacional, y Banda de M\u00fasicos de la Direcci\u00f3n Nacional de la Educaci\u00f3n Policial.<\/p>\n\n\n\n<p>Posteriormente a las 12 horas, interpretaci\u00f3n del Himno Nacional por la Orquesta Departamental.<\/p>\n\n\n\n<p>A continuaci\u00f3n palabras de las autoridades y en el cierre un Contrapunto de Bandas.<\/p>\n\n\n\n<p>Al finalizar el acto compartir\u00e1n con los vecinos la torta del 117\u00ba aniversario de Punta del Este, elaborada por la Escuela de Alta Gastronom\u00eda Parador Pedro Figari.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>FUENTE: INTENDENCIA DE MALDONADO<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes 5 de julio se celebra el 117\u00ba aniversario de la ciudad. El Municipio a trav\u00e9s del alcalde Javier Carballal, concejales y funcionarios, invitan a participar a la poblaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7364,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-7363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sector-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Punta del Este prepara los festejos de sus 117 a\u00f1os<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Punta del Este prepara los festejos de sus 117 a\u00f1os\" \/>\n<meta property=\"og:description\" content=\"Este viernes 5 de julio se celebra el 117\u00ba aniversario de la ciudad. El Municipio a trav\u00e9s del alcalde Javier Carballal, concejales y funcionarios, invitan a participar a la poblaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T17:03:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-04T17:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"grupoceo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"grupoceo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/\",\"url\":\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/\",\"name\":\"Punta del Este prepara los festejos de sus 117 a\u00f1os\",\"isPartOf\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg\",\"datePublished\":\"2024-07-04T17:03:13+00:00\",\"dateModified\":\"2024-07-04T17:03:15+00:00\",\"author\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/28fe5dbc1d4c1030d780a5ff0736f786\"},\"breadcrumb\":{\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#primaryimage\",\"url\":\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg\",\"contentUrl\":\"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg\",\"width\":2560,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/gopunta.uy\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Punta del Este prepara los festejos de sus 117 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/#website\",\"url\":\"https:\/\/gopunta.uy\/noticias\/\",\"name\":\"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado\",\"description\":\"Noticias del Portal Inmobiliario GoPunta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gopunta.uy\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/28fe5dbc1d4c1030d780a5ff0736f786\",\"name\":\"grupoceo\",\"sameAs\":[\"http:\/\/grupoceo.uy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Punta del Este prepara los festejos de sus 117 a\u00f1os","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Punta del Este prepara los festejos de sus 117 a\u00f1os","og_description":"Este viernes 5 de julio se celebra el 117\u00ba aniversario de la ciudad. El Municipio a trav\u00e9s del alcalde Javier Carballal, concejales y funcionarios, invitan a participar a la poblaci\u00f3n [&hellip;]","og_url":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/","og_site_name":"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado","article_published_time":"2024-07-04T17:03:13+00:00","article_modified_time":"2024-07-04T17:03:15+00:00","og_image":[{"width":2560,"height":1700,"url":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg","type":"image\/jpeg"}],"author":"grupoceo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"grupoceo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/","url":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/","name":"Punta del Este prepara los festejos de sus 117 a\u00f1os","isPartOf":{"@id":"https:\/\/gopunta.uy\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#primaryimage"},"image":{"@id":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg","datePublished":"2024-07-04T17:03:13+00:00","dateModified":"2024-07-04T17:03:15+00:00","author":{"@id":"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/28fe5dbc1d4c1030d780a5ff0736f786"},"breadcrumb":{"@id":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#primaryimage","url":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg","contentUrl":"https:\/\/gopunta.uy\/noticias\/wp-content\/uploads\/2024\/07\/Peninsula-1-scaled.jpeg","width":2560,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/gopunta.uy\/noticias\/2024\/07\/04\/punta-del-este-prepara-los-festejos-de-sus-117-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gopunta.uy\/noticias\/"},{"@type":"ListItem","position":2,"name":"Punta del Este prepara los festejos de sus 117 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/gopunta.uy\/noticias\/#website","url":"https:\/\/gopunta.uy\/noticias\/","name":"Noticias - GoPunta - Portal Inmobiliario de Punta del Este - Maldonado","description":"Noticias del Portal Inmobiliario GoPunta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gopunta.uy\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gopunta.uy\/noticias\/#\/schema\/person\/28fe5dbc1d4c1030d780a5ff0736f786","name":"grupoceo","sameAs":["http:\/\/grupoceo.uy"]}]}},"_links":{"self":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts\/7363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/comments?post=7363"}],"version-history":[{"count":1,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts\/7363\/revisions"}],"predecessor-version":[{"id":7365,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/posts\/7363\/revisions\/7365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/media\/7364"}],"wp:attachment":[{"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/media?parent=7363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/categories?post=7363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gopunta.uy\/noticias\/wp-json\/wp\/v2\/tags?post=7363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}